{"id":28453,"date":"2018-07-24T00:00:00","date_gmt":"2018-07-24T00:00:00","guid":{"rendered":"http:\/\/dev.italcam.com.br\/noticia\/a-fiat-sente-o-fim-da-era-marchionne\/"},"modified":"2018-07-24T00:00:00","modified_gmt":"2018-07-24T00:00:00","slug":"a-fiat-sente-o-fim-da-era-marchionne","status":"publish","type":"post","link":"https:\/\/italcam.com.br\/it\/a-fiat-sente-o-fim-da-era-marchionne\/","title":{"rendered":"A Fiat sente o fim da &#8216;era Marchionne&#8217;"},"content":{"rendered":"<p>Jornal do Brasil &#8211; Economia | Estad&atilde;o<\/p>\n<h1>A Fiat sente o fim da &#39;era Marchionne&#39;<\/h1>\n<p><span style=\"font-size:16px\"><span style=\"font-family:open sans\">A abrupta antecipa&ccedil;&atilde;o do fim de uma era na Fiat fez as a&ccedil;&otilde;es da montadora fecharem em queda nessa segunda-feira, 23, na Bolsa de Mil&atilde;o. Diretor-presidente da Fiat-Chrysler, que inclui ainda marcas como Ferrari e Jeep, Sergio Marchionne, 66 anos, foi afastado do comando do grupo ap&oacute;s sofrer complica&ccedil;&otilde;es de uma cirurgia e est&aacute; internado em estado cr&iacute;tico. O executivo &eacute; considerado o &quot;salvador&quot; da companhia, recuperando a multinacional italiana e transformando-a mais uma vez em uma pot&ecirc;ncia internacional.<\/span><\/span><\/p>\n<p><span style=\"font-size:16px\"><span style=\"font-family:open sans\">O baque foi sentido pela Fiat &#8211; cujas a&ccedil;&otilde;es chegaram a cair 4% no preg&atilde;o de segunda-feira, fechando em queda de 1,5% -, ainda que a aposentadoria de Marchionne estivesse programada para 2019. A companhia j&aacute; anunciou um substituto: Mike Manley, de 54 anos, vai assumir o grupo. Brit&acirc;nico, Manley vinha comandando os neg&oacute;cios nas marcas Jeep e os caminh&otilde;es Ram, duas das unidades mais rent&aacute;veis da Fiat.<\/span><\/span><\/p>\n<p><span style=\"font-size:16px\"><span style=\"font-family:open sans\">Quase uma d&eacute;cada e meia atr&aacute;s, ao entrar pela primeira vez na Fiat, Marchionne fez um diagn&oacute;stico nada lisonjeiro sobre a companhia: &quot;Esse lugar cheira a morte.&quot; Na &eacute;poca, o grupo somava d&iacute;vidas de \u0080 14 bilh&otilde;es, ap&oacute;s um preju&iacute;zo global de \u0080 1,6 bilh&atilde;o no ano anterior. A italiana era, ent&atilde;o, considerada uma empresa moribunda.<\/span><\/span><\/p>\n<p><span style=\"font-size:16px\"><span style=\"font-family:open sans\"><strong>A&ccedil;&otilde;es<\/strong><\/span><\/span><\/p>\n<p><span style=\"font-size:16px\"><span style=\"font-family:open sans\">At&eacute; ent&atilde;o desconhecido nos meios empresariais italianos, Marchionne foi descoberto pela fam&iacute;lia propriet&aacute;ria da montadora ap&oacute;s a morte de Umberto Agnelli, &uacute;ltimo do cl&atilde; a exercer a presid&ecirc;ncia. A recupera&ccedil;&atilde;o come&ccedil;ou com a renegocia&ccedil;&atilde;o de d&iacute;vidas e um choque de gest&atilde;o. Mesmo seus colaboradores mais pr&oacute;ximos eram observados e, eventualmente, defenestrados pelo chefe.<\/span><\/span><\/p>\n<p><span style=\"font-size:16px\"><span style=\"font-family:open sans\">Foi o que aconteceu com o todo-poderoso presidente da Ferrari Luca de Montezemolo, demitido em 2014 apesar de ter projetado a marca internacional da fabricante de autom&oacute;veis de luxo e constru&iacute;do uma escuderia vencedora na F&oacute;rmula 1, em parte gra&ccedil;as ao piloto Michael Schumacher.<\/span><\/span><\/p>\n<p><span style=\"font-size:16px\"><span style=\"font-family:open sans\">Ao longo dos anos de poder, Marchionne superou as resist&ecirc;ncias, renegociou de contratos trabalhistas, fechou f&aacute;bricas e conseguiu cortes de d&iacute;vidas e acordos inesperados para a inje&ccedil;&atilde;o de recursos no caixa da empresa.<\/span><\/span><\/p>\n<p><span style=\"font-size:16px\"><span style=\"font-family:open sans\">Em 2009, quando a Fiat ainda era considerada uma empresa em crise, e o setor automotivo enfrentava a turbul&ecirc;ncia financeira internacional, o empres&aacute;rio surpreendeu o mundo com a aquisi&ccedil;&atilde;o da Chrysler &#8211; e sem pagar nada por ela.<\/span><\/span><\/p>\n<p><span style=\"font-size:16px\"><span style=\"font-family:open sans\">Orgulho industrial italiano, a Fiat passou a ser negociada nas bolsas de valores de Wall Street e de Mil&atilde;o. Comandado a partir de Detroit, nos Estados Unidos, e de Turin, na It&aacute;lia, o novo grupo ganhou espa&ccedil;o e hoje vale mais de \u0080 60 bilh&otilde;es, dez vezes mais do que em 2004, em boa parte por causa da Jeep.<\/span><\/span><\/p>\n<p><span style=\"font-size:16px\"><span style=\"font-family:open sans\">Internado para uma cirurgia nos ombros descrita como banal, Marchionne agora est&aacute; internado em Zurique, na Su&iacute;&ccedil;a, em estado descrito pela companhia como &quot;irrevers&iacute;vel&quot;. Al&eacute;m de anunciar o novo presidente, John Elkann, neto de Gianni Agnelli, disc&iacute;pulo de Marchionne e diretor presidente do fundo Exor, holding familiar que det&eacute;m 30% da Fiat e 23% da Ferrari, assumir&aacute; a marca de autom&oacute;veis esportivos de luxo.&nbsp;<\/span><\/span><\/p>\n<p>Fonte:&nbsp;https:\/\/www.jb.com.br\/economia\/noticias\/2018\/07\/24\/a-fiat-sente-o-fim-da-era-marchionne\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jornal do Brasil &#8211; Economia | Estad&atilde;o A Fiat sente o fim da &#39;era Marchionne&#39; A abrupta antecipa&ccedil;&atilde;o do fim de uma [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[68],"class_list":["post-28453","post","type-post","status-publish","format-standard","hentry","category-notizie","tag-notizie-2018"],"_links":{"self":[{"href":"https:\/\/italcam.com.br\/it\/wp-json\/wp\/v2\/posts\/28453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/italcam.com.br\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/italcam.com.br\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/italcam.com.br\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/italcam.com.br\/it\/wp-json\/wp\/v2\/comments?post=28453"}],"version-history":[{"count":0,"href":"https:\/\/italcam.com.br\/it\/wp-json\/wp\/v2\/posts\/28453\/revisions"}],"wp:attachment":[{"href":"https:\/\/italcam.com.br\/it\/wp-json\/wp\/v2\/media?parent=28453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/italcam.com.br\/it\/wp-json\/wp\/v2\/categories?post=28453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/italcam.com.br\/it\/wp-json\/wp\/v2\/tags?post=28453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}