{"id":28359,"date":"2018-02-07T00:00:00","date_gmt":"2018-02-07T00:00:00","guid":{"rendered":"http:\/\/dev.italcam.com.br\/noticia\/il-brasile-a-milano-a-dialogo-le-opere-di-veio-e-oscar-niemeyer\/"},"modified":"2018-02-07T00:00:00","modified_gmt":"2018-02-07T00:00:00","slug":"il-brasile-a-milano-a-dialogo-le-opere-di-veio-e-oscar-niemeyer","status":"publish","type":"post","link":"https:\/\/italcam.com.br\/it\/il-brasile-a-milano-a-dialogo-le-opere-di-veio-e-oscar-niemeyer\/","title":{"rendered":"Il Brasile a Milano, a dialogo le opere di V\u00e9io e Oscar Niemeyer"},"content":{"rendered":"<p>La Repubblica | Casa &amp; Design<\/p>\n<h1>Il Brasile a Milano, a dialogo le opere di V&eacute;io e Oscar Niemeyer<\/h1>\n<p><span style=\"font-size:20px\"><span style=\"font-family:open sans\"><span style=\"background-color:rgb(255, 255, 255); color:rgb(51, 51, 51)\"><strong>Lo spazio dell&#39;Etel ospita una mostra che racconta la poliedrica cultura del progetto carioca<\/strong><\/span><\/span><\/span><\/p>\n<p><span style=\"font-size:20px\"><span style=\"font-family:open sans\">Brasile e Italia si incontrano a Milano. Per gli appassionati del&nbsp;design carioca&nbsp;l&rsquo;appuntamento &egrave;&nbsp;all&rsquo;Etel, uno spazio pensato&nbsp;per unire&nbsp;i due Paesi attraverso la promozione della cultura del progetto.&nbsp;A inaugurare la serie di eventi &egrave; la mostra&nbsp;<em>Tra arte e design &ndash; Un dialogo tra le opere di V&eacute;io e Oscar Niemeyer<\/em>&nbsp;in programma fino&nbsp;alla fine di marzo.<\/span><\/span><\/p>\n<div style=\"background:rgb(255, 255, 255); border:0px; padding:0px\">\n<p><span style=\"font-size:20px\"><span style=\"font-family:open sans\">L&rsquo;esposizione mette a confronto una selezione di opere di Cicero Alves dos Santos, in arte &ldquo;V&eacute;io&rdquo; &ndash; personaggio di grande rilievo nel panorama dell&rsquo;arte contemporanea brasiliana &ndash; con alcuni arredi di Oscar Niemeyer, maestro del modernismo brasiliano.&nbsp;Il risultato &egrave; molto interessante poich&eacute; il paragone tra i due creativi, che appartengono a mondi artistici lontani, raccontano bene il Brasile e la sua poliedrica cultura. Infatti alle linee pure ed eleganti&nbsp;degli arredi Oscar Niemeyer, V&eacute;io accosta 12 sculture enigmatiche composte da rami e legni, lavorati e&nbsp;dipinti con colori vivaci, che richiamano silhouette primitive di animali e uomini.<\/span><\/span><\/p>\n<div style=\"background:transparent; border:0px; padding:0px\"><span style=\"font-size:20px\"><span style=\"font-family:open sans\">Un articolo di&nbsp;design brasiliano,&nbsp;mostre,&nbsp;Tra arte e design &ndash; Un dialogo tra le opere di V&eacute;io e Oscar Niemeyer&nbsp;scritto da&nbsp;<span style=\"color:rgb(0, 0, 0)\">Valentina Ferlazzo<\/span>&nbsp;il 7 febbraio 2018<\/span><\/span><\/div>\n<div style=\"background:transparent; border:0px; padding:0px\">&nbsp;<\/div>\n<div style=\"background:transparent; border:0px; padding:0px\"><span style=\"font-size:20px\"><span style=\"font-family:open sans\">Fonte:&nbsp;<\/span><\/span>http:\/\/design.repubblica.it\/2018\/02\/07\/il-brasile-a-milano-a-dialogo-le-opere-di-veio-e-oscar-niemeyer\/#1<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Repubblica | Casa &amp; Design Il Brasile a Milano, a dialogo le opere di V&eacute;io e Oscar Niemeyer Lo spazio dell&#39;Etel [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[68],"class_list":["post-28359","post","type-post","status-publish","format-standard","hentry","category-notizie","tag-notizie-2018"],"_links":{"self":[{"href":"https:\/\/italcam.com.br\/it\/wp-json\/wp\/v2\/posts\/28359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/italcam.com.br\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/italcam.com.br\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/italcam.com.br\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/italcam.com.br\/it\/wp-json\/wp\/v2\/comments?post=28359"}],"version-history":[{"count":0,"href":"https:\/\/italcam.com.br\/it\/wp-json\/wp\/v2\/posts\/28359\/revisions"}],"wp:attachment":[{"href":"https:\/\/italcam.com.br\/it\/wp-json\/wp\/v2\/media?parent=28359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/italcam.com.br\/it\/wp-json\/wp\/v2\/categories?post=28359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/italcam.com.br\/it\/wp-json\/wp\/v2\/tags?post=28359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}